{"id":2813,"date":"2026-05-23T14:20:11","date_gmt":"2026-05-23T14:20:11","guid":{"rendered":"https:\/\/radioiep.com\/?p=2813"},"modified":"2026-05-23T14:20:11","modified_gmt":"2026-05-23T14:20:11","slug":"campanha-balaio-verde-promove-cortejo-no-dia-01-de-fevereiro","status":"publish","type":"post","link":"https:\/\/radioiep.com\/site\/campanha-balaio-verde-promove-cortejo-no-dia-01-de-fevereiro\/","title":{"rendered":"Campanha Balaio Verde promove Cortejo no dia 01 de fevereiro"},"content":{"rendered":"<p>Campanha Balaio Verde promove Cortejo no dia 01 de fevereiro<\/p>\n<p>A Campanha Balaio Verde est\u00e1 promovendo um Cortejo pela preserva\u00e7\u00e3o das praias limpas e uni\u00e3o dos povos, na Festa de Iemanj\u00e1, trazendo muitas performances art\u00edsticas e causas socioambientais.<\/p>\n<p>A a\u00e7\u00e3o, que \u00e9 coordenada pela produtora cultural Luzia Moraes, tem como objetivo orientar a sociedade para a manuten\u00e7\u00e3o do equil\u00edbrio marinho, buscando a redu\u00e7\u00e3o do impacto ambiental do tradicional presente de Iemanj\u00e1.<\/p>\n<p>A a\u00e7\u00e3o vem pelo segundo ano consecutivo em parceria com o artista pl\u00e1stico e ambientalista Andr\u00e9 Fernandes e seu projeto &#8220;Movimento Onda de Pl\u00e1stico\u201d, que promove a sensibiliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o sobre a limpeza e preserva\u00e7\u00e3o das praias. Andr\u00e9 levar\u00e1 uma escultura de Iemanj\u00e1 feita de res\u00edduos pl\u00e1sticos retirados do mar para desfilar.<\/p>\n<p>O Cortejo tamb\u00e9m \u00e9 em prol da divulga\u00e7\u00e3o da campanha \u201cCarnaval Sem Fome\u201d, organizada pela ONG A\u00e7\u00e3o da Cidadania que tem Raimundo Bandeira como coordenador e visa o combate as desigualdades sociais e incentiva a tomada de consci\u00eancia em rela\u00e7\u00e3o \u00e0 fome e \u00e0 pobreza.<\/p>\n<p>Urso da Montanha estar\u00e1 conduzindo a &#8220;Ala Xam\u00e2nica&#8221;, conhecida como &#8220;M\u00fasica Medicina&#8221;, de eleva\u00e7\u00e3o vibracional.<\/p>\n<p>A concentra\u00e7\u00e3o ser\u00e1 na frente ao Espa\u00e7o Jubiabar, na Rua da Paci\u00eancia, no Rio Vermelho, \u00e0s 21h.<\/p>\n<p>Servi\u00e7o<\/p>\n<p>Data: 01 de Fevereiro (s\u00e1bado)<br \/>\nConcentra\u00e7\u00e3o: \u00e0s 21h<br \/>\nSa\u00edda: \u00e0s 22h<br \/>\nLocal da Concentra\u00e7\u00e3o: Jubiabar , Rua Conselheiro Pedro Luiz, 79, no Rio Vermelho<br \/>\nCortejo: at\u00e9 a Casa de Iemanj\u00e1<br \/>\nCamisas: Para convidados;<\/p>\n<p>Apoio: SECIS, Andr\u00e9 Fraga (Vereador), UNEB, Movimento Onda de Pl\u00e1stico, Jubiabar, Boteco do Crioulo, Revista PeopleNews, Portal Caf\u00e9 com Shah, Marta Fox: A \u00danica, ShayraModel Collection, Deo Carvalho, Podcast &#8220;PodEmerson?&#8221;, A\u00e7\u00e3o da Cidadania Salvador, ASR Constru\u00e7\u00f5es Sustent\u00e1veis, IODDEB; Hidro Capoeira, HECAM, Coletivo Gente que Brilha, R\u00e1dio Vai Vai Brasile It\u00e1lia, Zermatten Productions, ONG ABEALUX, Revista Magazine e A\u00e7\u00e3o, R\u00e1dio Doinha Prata FM, B\u00fazio e ART, Essential Design e Casa da Noiva e Pousada Terap\u00eautica Mangar\u00e1.<\/p>\n<p id=\"rop\"><small>Originally posted 2025-01-31 18:58:58. <\/small><\/p>","protected":false},"excerpt":{"rendered":"<p>Campanha Balaio Verde promove Cortejo no dia 01 de fevereiro A Campanha Balaio Verde est\u00e1 promovendo um Cortejo pela preserva\u00e7\u00e3o das praias limpas e uni\u00e3o dos povos, na Festa de Iemanj\u00e1, trazendo muitas performances art\u00edsticas e causas socioambientais. A a\u00e7\u00e3o, que \u00e9 coordenada pela produtora cultural Luzia Moraes, tem como objetivo orientar a sociedade para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos"],"_links":{"self":[{"href":"https:\/\/radioiep.com\/site\/wp-json\/wp\/v2\/posts\/2813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioiep.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioiep.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioiep.com\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radioiep.com\/site\/wp-json\/wp\/v2\/comments?post=2813"}],"version-history":[{"count":0,"href":"https:\/\/radioiep.com\/site\/wp-json\/wp\/v2\/posts\/2813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioiep.com\/site\/wp-json\/wp\/v2\/media\/2814"}],"wp:attachment":[{"href":"https:\/\/radioiep.com\/site\/wp-json\/wp\/v2\/media?parent=2813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioiep.com\/site\/wp-json\/wp\/v2\/categories?post=2813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioiep.com\/site\/wp-json\/wp\/v2\/tags?post=2813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}